{"id":7750,"date":"2022-02-03T12:49:56","date_gmt":"2022-02-03T12:49:56","guid":{"rendered":"https:\/\/investate.be\/property\/student-rooms-sterrestraat-16\/"},"modified":"2026-03-10T09:46:53","modified_gmt":"2026-03-10T09:46:53","slug":"student-rooms-sterrestraat-16","status":"publish","type":"property","link":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/","title":{"rendered":"Student rooms Hasselt: Sterrestraat 16"},"content":{"rendered":"\n<p>LAST ROOM AVAILABLE FOR AY 2026 &#8211; 2027<\/p>\n\n\n\n<p>On the hunt for a luxurious and comfortable dorm room or studio nearby the city centre of Hasselt? Then you came to the right address. These rooms offer the best of both worlds. On the one hand, you can enjoy the privacy and coziness which are accompanied with a small-scale student residence. On the other hand, one must not compromise on the ambient student atmosphere due to the cozy terrace outside. The large communal courtyard, which is shared with 2 other student houses in our portfolio, offers the opportunity to socialize and build new friendships with fellow students.<\/p>\n\n\n\n<p>This student residence consists of 2 fully equipped and furnished studios as well as two superior student rooms. These last 2 rooms only need to share the kitchen facilities as well as the toilet. The size of the rooms differ from 15 to 35 m2. Depending on the room type, rental prices range from 530 EUR to 640 EUR per month including all charges. So costs concerning water-, gas- and electricity consumption, Wi-Fi, cleaning services, garbage collection, etc. are all covered.<\/p>\n\n\n\n<p>All rooms are equipped with a bed, desk and closet.<\/p>\n\n\n\n<p>Rooms will be available as of the first of September 2026. Please note that the attached list of rooms is subject to availability.<\/p>\n\n\n\n<p>Are you charmed by one of these rooms? Mail to <a href=\"mailto:aurelie@geckoinvest.be\">info@investate.be<\/a> or call <a href=\"tel:+3289209485\">089 20 94 85<\/a>.<\/p>\n\n\n\n<p><em>OPTIONAL: STUDENT PACKAGES<\/em><\/p>\n\n\n\n<p>Do you prefer a total peace of mind during your stay abroad? Then we may \u2018unburden\u2019 you by making your move as easy and convenient as possible by offering following packages:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kitchen package: everything you need in order to unleash your inner kitchen prince or princess<\/li>\n\n\n\n<li>Sleeping package: Everything you might need to get a good night of rest such as sleeping beauty. You only need to bring your own earbuds.<\/li>\n\n\n\n<li>New or second-hand desk chair<\/li>\n\n\n\n<li>New or second-hand mattress<\/li>\n<\/ul>\n\n\n\n<p>Please note that these packages are offered without any obligations. More information on the content and pricing of these packages can be found attached.<\/p>\n<a class=\"simplefavorite-button\" data-postid=\"7750\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;color:#ffffff;\"><i class=\"fas fa-heart\"><\/i><\/a>","protected":false},"excerpt":{"rendered":"<p>LAST ROOM AVAILABLE FOR AY 2026 &#8211; 2027 On the hunt for a luxurious and comfortable dorm room or studio nearby the city centre of Hasselt? Then you came to the right address. These rooms offer the best of both worlds. On the one hand, you can enjoy the privacy and coziness which are accompanied&#8230;<\/p>\n","protected":false},"author":3,"featured_media":6426,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-features":[162,154,156,160,158],"property-types":[134],"property-cities":[116],"property-statuses":[117],"class_list":["post-7750","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-all-charges-included","property-feature-bicycle-storage","property-feature-common-courtyard","property-feature-furnished","property-feature-intercom","property-type-student-room","property-city-hasselt-en","property-status-rented"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Student rooms Hasselt: Sterrestraat 16 - Investate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Student rooms Hasselt: Sterrestraat 16 - Investate\" \/>\n<meta property=\"og:description\" content=\"LAST ROOM AVAILABLE FOR AY 2026 &#8211; 2027 On the hunt for a luxurious and comfortable dorm room or studio nearby the city centre of Hasselt? Then you came to the right address. These rooms offer the best of both worlds. On the one hand, you can enjoy the privacy and coziness which are accompanied...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Investate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InvestateBV\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T09:46:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/\",\"url\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/\",\"name\":\"Student rooms Hasselt: Sterrestraat 16 - Investate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/investate.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/investate.be\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg\",\"datePublished\":\"2022-02-03T12:49:56+00:00\",\"dateModified\":\"2026-03-10T09:46:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/#primaryimage\",\"url\":\"https:\\\/\\\/investate.be\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/investate.be\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/investate.be\\\/en\\\/property\\\/student-rooms-sterrestraat-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/investate.be\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Student rooms Hasselt: Sterrestraat 16\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/investate.be\\\/#website\",\"url\":\"https:\\\/\\\/investate.be\\\/\",\"name\":\"Investate\",\"description\":\"We invest in real estate for you\",\"publisher\":{\"@id\":\"https:\\\/\\\/investate.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/investate.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/investate.be\\\/#organization\",\"name\":\"Investate\",\"url\":\"https:\\\/\\\/investate.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/investate.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/investate.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/nieuw-logo.png\",\"contentUrl\":\"https:\\\/\\\/investate.be\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/nieuw-logo.png\",\"width\":1717,\"height\":1482,\"caption\":\"Investate\"},\"image\":{\"@id\":\"https:\\\/\\\/investate.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InvestateBV\",\"https:\\\/\\\/www.instagram.com\\\/investate.be\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Student rooms Hasselt: Sterrestraat 16 - Investate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/","og_locale":"en_US","og_type":"article","og_title":"Student rooms Hasselt: Sterrestraat 16 - Investate","og_description":"LAST ROOM AVAILABLE FOR AY 2026 &#8211; 2027 On the hunt for a luxurious and comfortable dorm room or studio nearby the city centre of Hasselt? Then you came to the right address. These rooms offer the best of both worlds. On the one hand, you can enjoy the privacy and coziness which are accompanied...","og_url":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/","og_site_name":"Investate","article_publisher":"https:\/\/www.facebook.com\/InvestateBV","article_modified_time":"2026-03-10T09:46:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/","url":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/","name":"Student rooms Hasselt: Sterrestraat 16 - Investate","isPartOf":{"@id":"https:\/\/investate.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/#primaryimage"},"image":{"@id":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/#primaryimage"},"thumbnailUrl":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg","datePublished":"2022-02-03T12:49:56+00:00","dateModified":"2026-03-10T09:46:53+00:00","breadcrumb":{"@id":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/#primaryimage","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg","contentUrl":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-2-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/investate.be\/en\/property\/student-rooms-sterrestraat-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Properties","item":"https:\/\/investate.be\/property\/"},{"@type":"ListItem","position":2,"name":"Student rooms Hasselt: Sterrestraat 16"}]},{"@type":"WebSite","@id":"https:\/\/investate.be\/#website","url":"https:\/\/investate.be\/","name":"Investate","description":"We invest in real estate for you","publisher":{"@id":"https:\/\/investate.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/investate.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/investate.be\/#organization","name":"Investate","url":"https:\/\/investate.be\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/investate.be\/#\/schema\/logo\/image\/","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/12\/nieuw-logo.png","contentUrl":"https:\/\/investate.be\/wp-content\/uploads\/2021\/12\/nieuw-logo.png","width":1717,"height":1482,"caption":"Investate"},"image":{"@id":"https:\/\/investate.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InvestateBV","https:\/\/www.instagram.com\/investate.be\/"]}]}},"property_meta":{"REAL_HOMES_property_price":"530","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"From","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"","REAL_HOMES_property_size_postfix":"","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"","REAL_HOMES_property_bathrooms":"","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"1","REAL_HOMES_additional_details_list":[["Room Types","Superior - Deluxe"],["Number of Rooms","4"],["Price Range","\u20ac 530 - \u20ac 640"],["Room Surface","15 - 35 m2"]],"REAL_HOMES_property_location":{"latitude":"50.93145585","longitude":"5.3479308674023","zoom":"9"},"REAL_HOMES_property_address":"16, Sterrestraat, Sint-Catharinawijk, Runkst, Hasselt, Limburg, Flanders, 3500, Belgium","REAL_HOMES_property_map":"","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-1240x720.jpg"}},"image_meta":{"aperture":"9","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630425734","copyright":"","focal_length":"15","iso":"100","shutter_speed":"0.0025","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1.jpg","ID":"6425","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Exterieur (1)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-1240x720.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630409630","copyright":"","focal_length":"15","iso":"500","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2.jpg","ID":"6437","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Kamer 1 (2)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-1-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-1240x720.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630410410","copyright":"","focal_length":"15","iso":"200","shutter_speed":"0.0125","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3.jpg","ID":"6440","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Kamer 3 (3)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-1240x720.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630410346","copyright":"","focal_length":"15","iso":"125","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1.jpg","ID":"6438","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Kamer 3 (1)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-1240x720.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630410373","copyright":"","focal_length":"15","iso":"400","shutter_speed":"0.0125","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2.jpg","ID":"6439","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Kamer 3 (2)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-1240x720.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630410914","copyright":"","focal_length":"15","iso":"1000","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4.jpg","ID":"6441","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Kamer 3 (4)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-1536x1024.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630410932","copyright":"","focal_length":"15","iso":"200","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5.jpg","ID":"6442","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Kamer-3-5-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Kamer 3 (5)","caption":"","description":"","alt":"","srcset":false},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-1240x720.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630409360","copyright":"","focal_length":"15","iso":"100","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5.jpg","ID":"6434","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Interieur Gemeenschap (5)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Interieur-Gemeenschap-5-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-scaled.jpg","sizes":{"medium":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-300x200.jpg"},"large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-1024x683.jpg"},"thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-150x150.jpg"},"medium_large":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-768x512.jpg"},"1536x1536":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-1536x1024.jpg"},"2048x2048":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-2048x1365.jpg"},"post-thumbnail":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-150x100.jpg"},"modern-property-child-slider":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-680x510.jpg"},"property-thumb-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-488x326.jpg"},"property-detail-video-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-818x417.jpg"},"agent-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-210x210.jpg"},"post-featured-image":{"file":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-1240x720.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"Canon EOS M50m2","caption":"","created_timestamp":"1630406727","copyright":"","focal_length":"15","iso":"100","shutter_speed":"0.00625","title":"","orientation":"1","keywords":[]},"original_image":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1.jpg","ID":"6428","name":"Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-scaled.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-scaled.jpg","url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-150x150.jpg","full_url":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-scaled.jpg","title":"Opbrengsteigendommen Studentenhuizen Hasselt Area Dusartplein Sterrestraat 16 Exterieur Gemeenschap (1)","caption":"","description":"","alt":"","srcset":"https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-150x150.jpg 150w, https:\/\/investate.be\/wp-content\/uploads\/2021\/09\/Opbrengsteigendommen-Studentenhuizen-Hasselt-Area-Dusartplein-Sterrestraat-16-Exterieur-Gemeenschap-1-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"1","REAL_HOMES_gallery_slider_type":"thumb-on-bottom","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"global","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"","inspiry_additional_fee":"","REAL_HOMES_attachments":[{"filesize":68813,"ID":"9313","name":"Student-Packages-AY-2023-2024.pdf","path":"\/var\/www\/html\/wp-content\/uploads\/2022\/02\/Student-Packages-AY-2023-2024.pdf","url":"https:\/\/investate.be\/wp-content\/uploads\/2022\/02\/Student-Packages-AY-2023-2024.pdf","title":"Student Packages AY 2023-2024"},{"filesize":54594,"ID":"11206","name":"Rental-prices-Sterrestraat-16-AY-2026-2027.pdf","path":"\/var\/www\/html\/wp-content\/uploads\/2022\/02\/Rental-prices-Sterrestraat-16-AY-2026-2027.pdf","url":"https:\/\/investate.be\/wp-content\/uploads\/2022\/02\/Rental-prices-Sterrestraat-16-AY-2026-2027.pdf","title":"Rental prices Sterrestraat 16 AY 2026 &#8211; 2027"}],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","inspiry_global_property_template_override":"0","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","inspiry_type_kamer":[],"inspiry_type_of_room":["Superior","Deluxe"],"inspiry_bemeubeld":"","inspiry_furniture":"Yes","inspiry_tuin\/terras":"","inspiry_garden\/terrace":"Yes","REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_custom_footer_display":"default","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/properties\/7750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/comments?post=7750"}],"version-history":[{"count":23,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/properties\/7750\/revisions"}],"predecessor-version":[{"id":11208,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/properties\/7750\/revisions\/11208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/media\/6426"}],"wp:attachment":[{"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/media?parent=7750"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/property-features?post=7750"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/property-types?post=7750"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/property-cities?post=7750"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/investate.be\/en\/wp-json\/wp\/v2\/property-statuses?post=7750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}